{"id":818,"date":"2022-10-28T17:00:10","date_gmt":"2022-10-28T15:00:10","guid":{"rendered":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/?p=818"},"modified":"2022-12-12T11:00:06","modified_gmt":"2022-12-12T10:00:06","slug":"einzelne-fliesen-austauschen","status":"publish","type":"post","link":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/","title":{"rendered":"Einzelne Fliesen austauschen"},"content":{"rendered":"<h2>\u00ab So lassen sich schadhafte Wand- und Bodenfliesen instand setzen \u00bb<\/h2>\n<p style=\"text-align: justify;\"><strong>Fliese kaputt? Das ist \u00e4rgerlich, aber kein Grund zur Panik. Entspannt zum Alltag \u00fcbergehen sollten Sie allerdings trotzdem nicht. Kleine Macken, Risse und Spr\u00fcnge in Wand- und <\/strong><a href=\"https:\/\/www.fliesen-onlineshop24.de\/bodenfliesen\/\"><strong>Bodenfliesen<\/strong><\/a><strong> st\u00f6ren nicht nur die Optik in K\u00fcche, Wohn- oder Badezimmer, sondern k\u00f6nnen auf lange Sicht gr\u00f6\u00dfere Sch\u00e4den nach sich ziehen. Keine Sorge: Die meisten Besch\u00e4digungen sind kein Grund, sofort den Fliesenleger zu rufen. Einzelne Fliesen austauschen, das ist mit etwas Know-how und dem richtigen Werkzeug kein Hexenwerk. Wir erkl\u00e4ren Ihnen, wie es geht:<\/strong><\/p>\n<h2>Vorsorge treffen: Reservefliesen aufheben<\/h2>\n<p style=\"text-align: justify;\">Zugegeben: Dieser Tipp kommt manchmal zu sp\u00e4t. Wer beim Verfliesen von Fu\u00dfboden, K\u00fcche und Bad stets einige Ersatzfliesen bestellt und sicher verwahrt hat, kann im Fall des Falles mit dem Austauschen der Fliesen sofort beginnen. G\u00e4ngige Fliesentypen lassen sich zwar auch sp\u00e4ter nachbestellen, aber ein kleiner Vorrat an Ersatzfliesen spart Zeit und Nerven, denn im Schadensfall hat man selten Lust, auch noch umst\u00e4ndlich nach der passenden Fliese zu suchen. Au\u00dferdem weichen selbst die nachbestellten Fliesen der gleichen Serie in der Regel leicht von den alten Fliesen ab, da sie aus einer anderen Charge stammen. Dies ist bei Wand- oder Bodenfliesen durch den Herstellungsprozess bedingt. Ein weiter Grund daf\u00fcr, dass man idealerweise ein paar Reservefliesen der gleichen Charge daheim auf Lager hat.<\/p>\n<p style=\"text-align: justify;\">Neben der passenden Ersatzfliese brauchen Sie f\u00fcr den Fliesenaustausch <a href=\"https:\/\/www.fliesen-onlineshop24.de\/zubehoer\/\">geeignetes Werkzeug und Fliesenzubeh\u00f6r<\/a>.<\/p>\n<figure id=\"attachment_845\" aria-describedby=\"caption-attachment-845\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-845 size-full\" title=\"Beim Kauf von Fliesen sollte man unbedingt ein paar Fliesen zur Seite nehmen und einlagern\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Stapel-mit-Fliesen.jpg\" alt=\"Stapel an neuen Fliesen\" width=\"900\" height=\"530\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Stapel-mit-Fliesen.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Stapel-mit-Fliesen-300x177.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Stapel-mit-Fliesen-768x452.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-845\" class=\"wp-caption-text\">\u00a9 Wiktor Fedorenko &#8211; stock.adobe.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Vieles, aber sicher nicht alles aus dieser Materialliste ist in Ihrem Hobbykeller vorhanden. Legen Sie sich das ben\u00f6tigte Werkzeug bereit, um l\u00e4stigen Unterbrechungen vorzubeugen.<\/p>\n<p style=\"text-align: justify;\">Los geht&#8217;s: Diese Werkzeuge und Materialen brauchen Sie zum Fliesen austauschen:<\/p>\n<ul>\n<li>Cutter- oder Fugenmesser (evtl. Rasierklinge)<\/li>\n<li>Sto\u00dfspachtel<\/li>\n<li>Malerspachtel<\/li>\n<li>Schutzbrille<\/li>\n<li>Schlosser- und Fliesenhammer<\/li>\n<li>Fliesenmei\u00dfel und Spitzmei\u00dfel<\/li>\n<li>Ma\u00dfband<\/li>\n<li>Wasserwaage<\/li>\n<li>Bleistift<\/li>\n<li>Zahnkelle<\/li>\n<li>Putzschwamm<br \/>\n<a href=\"https:\/\/www.fliesen-onlineshop24.de\/codex-x-fusion-werkzeugset\/11524835\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-143 size-full aligncenter\" title=\"Codex X-Fusion Werkzeugset\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/06\/Codex-X-Fusion-Werkzeugset.jpg\" alt=\"Codex X-Fusion Werkzeugset\" width=\"546\" height=\"459\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/06\/Codex-X-Fusion-Werkzeugset.jpg 546w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/06\/Codex-X-Fusion-Werkzeugset-300x252.jpg 300w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/a><\/li>\n<li>Kartuschepistole + 1 Kartusche Silikon und Acryl<\/li>\n<li>Flex mit Diamanttrennscheibe<\/li>\n<li>Holzkeile bzw. Fugenkreuze<\/li>\n<li>Malerkrepp<\/li>\n<li><a href=\"https:\/\/www.fliesen-onlineshop24.de\/zubehoer\/fliesenkleber-bauchemie\/\">Fliesenkleber und Fugenm\u00f6rtel<\/a><\/li>\n<li>Wasser<\/li>\n<li>Seifenlauge<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/codex-power-cx-7-14-kg-multi-flex-moertel\/11524808\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-840 \" title=\"Codex Power CX 7 14 kg Multi-Flex-M\u00f6rtel\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/codex-power-cx-7-14-kg-multi-flex-moertel-2.jpg\" alt=\"Codex Power CX 7 14 kg Multi-Flex-M\u00f6rtel\" width=\"299\" height=\"563\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/codex-power-cx-7-14-kg-multi-flex-moertel-2.jpg 400w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/codex-power-cx-7-14-kg-multi-flex-moertel-2-159x300.jpg 159w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" \/><\/a><\/p>\n<h2>1. Schritt beim Fliesen austauschen: Fugenentfernung<\/h2>\n<p style=\"text-align: justify;\">Ehe Sie die besch\u00e4digte Boden- oder <a href=\"https:\/\/www.fliesen-onlineshop24.de\/wandfliesen\/\">Wandfliese<\/a> herausl\u00f6sen k\u00f6nnen, m\u00fcssen Sie die rundherum vorhandenen Fugen vorsichtig entfernen. Das klappt am besten mit einem Fugen- oder Cuttermesser. Auch eine Rasierklinge kann besonders bei Silikonfugen gute Dienste leisten. Wir empfehlen, die Fliesen rund um die kaputte Fliese vorsorglich mit Malerkrepp abzukleben. So verhindern Sie, dass bei der Entfernung weitere Kacheln besch\u00e4digt werden.<\/p>\n<figure id=\"attachment_824\" aria-describedby=\"caption-attachment-824\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-824 size-full\" title=\"Harte Fugen lassen sich mit einem Fugenkratzer gut entfernen\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fugenkratzer.jpg\" alt=\"Jemand nutzt Fugenkratzer an Wandfliese\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fugenkratzer.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fugenkratzer-300x200.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fugenkratzer-768x512.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-824\" class=\"wp-caption-text\">\u00a9 Dmitriy Melnikov &#8211; stock.adobe.com<\/figcaption><\/figure>\n<h2>2. Schritt: Wie Sie kaputte Fliesen entfernen<\/h2>\n<p style=\"text-align: justify;\">Achtung: Wenn Sie kaputte Fliesen mit Hammer und Mei\u00dfel entfernen, fliegen schon mal gef\u00e4hrliche Splitter durch die Luft. Eine Schutzbrille aufzusetzen, ist bei diesem Arbeitsschritt besonders wichtig. Auch die Profis tun das und als weniger ge\u00fcbter Heimwerker sollten Sie nicht unvorsichtig sein. Schlagen Sie nun mit dem Spitzmei\u00dfel oder Stemmeisen in der Mitte der zu entfernenden Kachel ein Loch und l\u00f6sen Sie nach und nach von innen nach au\u00dfen systematisch alle Fliesenteile. Das geht manchmal wie von selbst, manchmal ist etwas mehr Kraft und\/oder Fingerspitzengef\u00fchl n\u00f6tig. Entfernen Sie unbedingt auch den verbliebenen M\u00f6rtel und Fugenm\u00f6rtel sehr sorgf\u00e4ltig. F\u00fcr ein gutes Ergebnis muss der Untergrund f\u00fcr die neue Wand- oder Bodenfliese sauber und glatt sein. Diese M\u00fche lohnt sich f\u00fcr alle, die sich nicht mit halben Sachen zufriedengeben.<\/p>\n<figure id=\"attachment_829\" aria-describedby=\"caption-attachment-829\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-829 size-full\" title=\"Bei der Fliesenentfernung ist eine Sicherheitsbrille alternativlos\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/FLiese-entfernen.jpg\" alt=\"jemand entfernt eine Bodenfliese mit Bohrmaschine und Mei\u00dfel\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/FLiese-entfernen.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/FLiese-entfernen-300x200.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/FLiese-entfernen-768x512.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-829\" class=\"wp-caption-text\">\u00a9 Aonprom Photo &#8211; stock.adobe.com<\/figcaption><\/figure>\n<h2>3. Schritt: neue Wand- oder Bodenfliese exakt zuschneiden<\/h2>\n<p style=\"text-align: justify;\">Den 3. Arbeitsschritt k\u00f6nnen Sie nat\u00fcrlich \u00fcberspringen, wenn Sie eine ganze Wand- oder Bodenfliese komplett austauschen k\u00f6nnen. Manchmal wird das Austauschen der Kacheln zur echten T\u00fcftelei: Leider bekommen n\u00e4mlich h\u00e4ufig genau die bereits f\u00fcr eine Zimmerecke zugeschnittenen Fliesen einen Riss oder Sprung. Sie sollten daher wissen, wie Sie eine Wand- oder Bodenfliese fachgerecht zuschneiden: Bekleben Sie die Kachel zur Sicherheit mit Malerkrepp und zeichnen Sie mit Bleistift die ben\u00f6tigten Ma\u00dfe exakt auf. S\u00e4gen Sie nun mit der Flex mit Diamantblatt die Kachel passend zur vorhandenen L\u00fccke im Fliesenspiegel zurecht. Genauigkeit ist beim Kacheln austauschen wie bei vielen Handwerkst\u00e4tigkeiten Trumpf. Es lohnt sich also, sorgf\u00e4ltig mit Ma\u00dfband und Wasserwaage zu arbeiten. Damit das Gesamtbild sp\u00e4ter akkurat und ansehnlich wird, kommt es jetzt auf jeden Millimeter an.<\/p>\n<figure id=\"attachment_831\" aria-describedby=\"caption-attachment-831\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-831 size-full\" title=\"F\u00fcr pr\u00e4zises Zurechtschneiden einer Fliese kann ein Winkelschleifer gute Dienste leisten\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliese-zurechtschneiden.jpg\" alt=\"Fliese wird mit Winkelschleifer zurechtgeschnitten\" width=\"900\" height=\"504\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliese-zurechtschneiden.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliese-zurechtschneiden-300x168.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliese-zurechtschneiden-768x430.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-831\" class=\"wp-caption-text\">\u00a9 andranik123 &#8211; stock.adobbe.com<\/figcaption><\/figure>\n<h2>4. Schritt beim Austauschen:\u00a0 So setzen Sie die neue Wand- oder Bodenfliese fachgerecht ein:<\/h2>\n<p style=\"text-align: justify;\">Tragen Sie Fliesenkleber in der entstandenen L\u00fccke auf und verstreichen Sie den Kleber gro\u00dfz\u00fcgig mit einem Zahnspachtel. Auch auf die R\u00fcckseite der neuen Fliese kommt der Fliesenkleber. Jetzt k\u00f6nnen Sie die Kachel vorsichtig einsetzen. Mit Fliesenkeilen bzw. Fugenkreuzen in den Zwischenr\u00e4umen stellen Sie sicher, dass die Abst\u00e4nde im Fliesenspiegel sp\u00e4ter genau passen. Solange der Kleber noch feucht ist, sind kleine Korrekturen problemlos m\u00f6glich. Wenn alles passt, ist etwas Geduld geboten: Ehe Sie zum n\u00e4chsten Arbeitsschritt \u00fcbergehen, muss der Fliesenkleber n\u00e4mlich sorgf\u00e4ltig durchtrocknen. Halten Sie sich hierbei genau an die Herstellerangaben auf der Verpackung.<\/p>\n<p><a href=\"\/urbanixx-gres-3d-fugenkreuz-50-stueck\/21551491\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-878\" title=\"System Leveling 3D Fugenkreuz - 50 St\u00fcck\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/system-leveling-3d-fugenkreuz-50-stueck.jpg\" alt=\"System Leveling 3D Fugenkreuz - 50 St\u00fcck\" width=\"524\" height=\"493\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/system-leveling-3d-fugenkreuz-50-stueck.jpg 600w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/system-leveling-3d-fugenkreuz-50-stueck-300x283.jpg 300w\" sizes=\"auto, (max-width: 524px) 100vw, 524px\" \/><\/a><\/p>\n<h2>5. Schritt beim Austauschen der Fliesen: die fachgerechte Verfugung<\/h2>\n<p style=\"text-align: justify;\">Wenn der Fliesenkleber getrocknet ist, k\u00f6nnen Sie mit der Verfugung Ihrer Wand- oder Bodenfliesen in K\u00fcche oder Bad beginnen: Entfernen Sie zun\u00e4chst die eingespannten Fliesenkeile bzw. Fugenkreuze. R\u00fchren Sie eine ausreichende Menge Fugenm\u00f6rtel in einem Eimer an. Streichen Sie diese Masse mit einer Maurerkelle satt in die Fugen. Wenn der M\u00f6rtel leicht getrocknet ist, sollten Sie den Fugenm\u00f6rtel mit Putzschwamm, Wasser und einem <a href=\"https:\/\/www.fliesen-onlineshop24.de\/zubehoer\/reinigung\/\">speziellen Zementschleierentferner<\/a> sorgf\u00e4ltig von den Fliesen abwaschen, bis keine R\u00fcckst\u00e4nde mehr vorhanden sind.<\/p>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/codex-pure-cem-ex-1-l-zementschleierentferner\/11521574\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-834\" title=\"Codex Pure Cem EX 1 L - Zementschleierentferner\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/codex-pure-cem-ex-1-l-zementschleierentferner-92x300.jpg\" alt=\"Codex Pure Cem EX 1 L - Zementschleierentferner\" width=\"139\" height=\"453\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Einen Sonderfall stellt der Wand- oder Deckenanschluss dar. Hier ist auch beim Austauschen eine Dehnungsfuge aus Silikon wichtig, um neuen Rissen vorzubeugen.<\/p>\n<h2>Einzelne Fliesen austauschen \u2013 f\u00fcr versierte Heimwerker kein Problem<\/h2>\n<p style=\"text-align: justify;\">Zugegeben: Das richtige Werkzeug, handwerkliches Geschick und etwas Know-how und Fingerspitzengef\u00fchl sind beim Austauschen von besch\u00e4digten Wand- oder Bodenfliesen tats\u00e4chlich n\u00f6tig. F\u00fcr begeisterte Heimwerker sind kaputte Fliesen zwar \u00e4rgerlich, geh\u00f6ren aber zu den Herausforderungen der einfacheren Art. Gehen Sie beim Austauschen systematisch nach unserer Schritt-f\u00fcr-Schritt-Anleitung vor &#8211; dann kann beim Austauschen kaputter Wand- oder Bodenfliesen wenig schiefgehen. Im Zweifel fragen Sie einfach bei unseren Fliesenexperten nach. Wir beraten Sie gern.<\/p>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/flaviker-re-tour-bodenfliese-betonoptik-ivory-matt-60x60-cm-rekt.-r10b\/11462474\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-843 size-full\" title=\"Flaviker Re_Tour Bodenfliese Betonoptik Ivory matt 60x60 cm rekt. R10B\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/flaviker-re-tour-bodenfliese-betonoptik-ivory-matt-1.jpg\" alt=\"Flaviker Re_Tour Bodenfliese Betonoptik Ivory matt 60x60 cm rekt. R10B\" width=\"900\" height=\"664\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/flaviker-re-tour-bodenfliese-betonoptik-ivory-matt-1.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/flaviker-re-tour-bodenfliese-betonoptik-ivory-matt-1-300x221.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/flaviker-re-tour-bodenfliese-betonoptik-ivory-matt-1-768x567.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab So lassen sich schadhafte Wand- und Bodenfliesen instand setzen \u00bb Fliese kaputt? Das ist \u00e4rgerlich, aber kein Grund zur Panik. Entspannt zum Alltag \u00fcbergehen sollten Sie allerdings trotzdem nicht. Kleine Macken, Risse und Spr\u00fcnge in Wand- und Bodenfliesen st\u00f6ren nicht nur die Optik in K\u00fcche, Wohn- oder Badezimmer, sondern k\u00f6nnen auf lange Sicht gr\u00f6\u00dfere &hellip;<\/p>\n","protected":false},"author":1,"featured_media":820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[151,159,158,157,160,103],"class_list":["post-818","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-praxistipps-diy","tag-einzelne-fliesen-austauschen","tag-ersatzfliesen","tag-fliese-austauschen","tag-fliese-gebrochen","tag-fliese-kaputt","tag-fliesen-verlegen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Einzelne Fliesen austauschen - Fliesen-Onlineshop24 Magazin<\/title>\n<meta name=\"description\" content=\"Schadhafte Fliesen selber austauschen, mit unserer \u2713Schritt-f\u00fcr-Schritt-Anleitung gelingt das Ausbessern ohne Probleme | Fliesen-Onlineshop24\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einzelne Fliesen austauschen - Fliesen-Onlineshop24 Magazin\" \/>\n<meta property=\"og:description\" content=\"Schadhafte Fliesen selber austauschen, mit unserer \u2713Schritt-f\u00fcr-Schritt-Anleitung gelingt das Ausbessern ohne Probleme | Fliesen-Onlineshop24\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/\" \/>\n<meta property=\"og:site_name\" content=\"Fliesen-Onlineshop24 Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-28T15:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-12T10:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wpadministrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpadministrator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/\",\"url\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/\",\"name\":\"Einzelne Fliesen austauschen - Fliesen-Onlineshop24 Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg\",\"datePublished\":\"2022-10-28T15:00:10+00:00\",\"dateModified\":\"2022-12-12T10:00:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7\"},\"description\":\"Schadhafte Fliesen selber austauschen, mit unserer \u2713Schritt-f\u00fcr-Schritt-Anleitung gelingt das Ausbessern ohne Probleme | Fliesen-Onlineshop24\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#primaryimage\",\"url\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg\",\"contentUrl\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg\",\"width\":900,\"height\":600,\"caption\":\"\u00a9 smilekorn - stock.adobe.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einzelne Fliesen austauschen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website\",\"url\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/\",\"name\":\"Fliesen-Onlineshop24 Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7\",\"name\":\"wpadministrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g\",\"caption\":\"wpadministrator\"},\"sameAs\":[\"http:\/\/magazin.fliesen-onlineshop24.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einzelne Fliesen austauschen - Fliesen-Onlineshop24 Magazin","description":"Schadhafte Fliesen selber austauschen, mit unserer \u2713Schritt-f\u00fcr-Schritt-Anleitung gelingt das Ausbessern ohne Probleme | Fliesen-Onlineshop24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/","og_locale":"de_DE","og_type":"article","og_title":"Einzelne Fliesen austauschen - Fliesen-Onlineshop24 Magazin","og_description":"Schadhafte Fliesen selber austauschen, mit unserer \u2713Schritt-f\u00fcr-Schritt-Anleitung gelingt das Ausbessern ohne Probleme | Fliesen-Onlineshop24","og_url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/","og_site_name":"Fliesen-Onlineshop24 Magazin","article_published_time":"2022-10-28T15:00:10+00:00","article_modified_time":"2022-12-12T10:00:06+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg","type":"image\/jpeg"}],"author":"wpadministrator","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"wpadministrator","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/","url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/","name":"Einzelne Fliesen austauschen - Fliesen-Onlineshop24 Magazin","isPartOf":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#primaryimage"},"image":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg","datePublished":"2022-10-28T15:00:10+00:00","dateModified":"2022-12-12T10:00:06+00:00","author":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7"},"description":"Schadhafte Fliesen selber austauschen, mit unserer \u2713Schritt-f\u00fcr-Schritt-Anleitung gelingt das Ausbessern ohne Probleme | Fliesen-Onlineshop24","breadcrumb":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#primaryimage","url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg","contentUrl":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2024\/10\/Fliesenentfernung.jpg","width":900,"height":600,"caption":"\u00a9 smilekorn - stock.adobe.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/einzelne-fliesen-austauschen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Einzelne Fliesen austauschen"}]},{"@type":"WebSite","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website","url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/","name":"Fliesen-Onlineshop24 Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7","name":"wpadministrator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g","caption":"wpadministrator"},"sameAs":["http:\/\/magazin.fliesen-onlineshop24.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":29,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts\/818\/revisions"}],"predecessor-version":[{"id":1146,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts\/818\/revisions\/1146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/media\/820"}],"wp:attachment":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/categories?post=818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/tags?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}