{"id":1652,"date":"2023-03-31T10:00:51","date_gmt":"2023-03-31T09:00:51","guid":{"rendered":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/?p=1652"},"modified":"2023-04-03T09:26:15","modified_gmt":"2023-04-03T08:26:15","slug":"grossformatige-fliesen-verlegen","status":"publish","type":"post","link":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/","title":{"rendered":"Gro\u00dfformatige Fliesen verlegen"},"content":{"rendered":"<h2>\u00ab Tipps zum Arbeiten mit XXL-Fliesen \u00bb<\/h2>\n<p style=\"text-align: justify;\"><strong>Scheinbar fugenlose B\u00e4der, elegante Wand- und Bodenkonzepte in Wohnr\u00e4umen \u2013 mit gro\u00dfformatigen Fliesen l\u00e4sst sich eine ruhige, klare und einzigartige Atmosph\u00e4re schaffen. Dank des geringen Fugenanteils dieser Wand- und <\/strong><a href=\"https:\/\/www.fliesen-onlineshop24.de\/bodenfliesen\/\"><strong>Bodenfliesen<\/strong><\/a><strong> bieten sie fantastische Gestaltungsm\u00f6glichkeiten. Ab einer Seitenl\u00e4nge von etwa 90 cm spricht man von XXL-Fliesen. Das umfasst sowohl Bodenfliesen als auch <\/strong><a href=\"https:\/\/www.fliesen-onlineshop24.de\/wandfliesen\/xxl-fliesen\/\"><strong>XXL-Wandfliesen<\/strong><\/a><strong>. Beim Verlegen m\u00fcssen einige Besonderheiten beachtet werden. Wir geben Ihnen Tipps f\u00fcr das Verlegen und stellen Ihnen diese trendigen Fliesenvarianten genauer vor. <\/strong><\/p>\n<h2>Ab welchem Format spricht man von XXL-Fliesen?<\/h2>\n<p style=\"text-align: justify;\">Gro\u00dfformatige Boden- oder Wandfliesen zu verlegen, wird mit zunehmender Gr\u00f6\u00dfe anspruchsvoller. Es gibt keine klar festgelegte Definition, ab welchen Ma\u00dfen eine Wand- oder Bodenfliese als XXL-Format bezeichnet wird. In der Regel spricht man ab einer Kantenl\u00e4nge von 90 cm von XXL-Fliesen. Nach oben sind in puncto L\u00e4nge kaum Grenzen gesetzt. Moderne Verarbeitungs- und Fertigungsverfahren machen mittlerweile Formate mit Kantenl\u00e4ngen von \u00fcber drei Metern m\u00f6glich.<\/p>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/vanezia-gres-mima-wandfliese-marmoroptik-gruen-weiss-matt-120x280-cm-rekt.-r10\/10532651\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1668 size-full\" title=\"Vanezia Gres Mima Wandfliese Marmoroptik Gr\u00fcn\/Wei\u00df matt 120x280 cm rekt. R10\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/vanezia-gres-mima-wandfliese-marmoroptik-gruen-weiss-matt-120x280-cm-rekt.-r10.jpg\" alt=\"Vanezia Gres Mima Wandfliese Marmoroptik Gr\u00fcn\/Wei\u00df matt 120x280 cm rekt. R10\" width=\"850\" height=\"1093\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/vanezia-gres-mima-wandfliese-marmoroptik-gruen-weiss-matt-120x280-cm-rekt.-r10.jpg 850w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/vanezia-gres-mima-wandfliese-marmoroptik-gruen-weiss-matt-120x280-cm-rekt.-r10-233x300.jpg 233w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/vanezia-gres-mima-wandfliese-marmoroptik-gruen-weiss-matt-120x280-cm-rekt.-r10-796x1024.jpg 796w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/vanezia-gres-mima-wandfliese-marmoroptik-gruen-weiss-matt-120x280-cm-rekt.-r10-768x988.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/a><\/p>\n<h2>Traumhafte Bad- und Wohnraumgestaltung<\/h2>\n<p style=\"text-align: justify;\">Wer sich f\u00fcr Riesenfliesen auf dem Boden oder XXL-Wandfliesen entscheidet, der kann faszinierende, scheinbar fugenlose Raumdesigns verwirklichen. Erh\u00e4ltlich sind die <a href=\"https:\/\/www.fliesen-onlineshop24.de\/wandfliesen\/\">Wandfliesen<\/a> sowohl anpoliert als auch matt und poliert. Die Auswahl an Designs l\u00e4sst keine W\u00fcnsche offen! So gibt es Beton-, Marmor-, Terrazzo- und weitere Gro\u00dfformat-Optiken, die Sie sicher begeistern werden. Mit raffinierten 3-D- und <a href=\"https:\/\/www.fliesen-onlineshop24.de\/bodenfliesen\/metalloptik\/\">Metall-Fliesenoptiken<\/a> lassen sich auch extravagante Raumdesigns verwirklichen, die f\u00fcr das gewisse Extra sorgen. Allerdings halten die Verlegearbeiten mit Riesenfliesen auch einige Herausforderungen bereit, die bei kleineren Fliesenformaten keine Rolle spielen. Deswegen sollte man beim Verlegen der gro\u00dfformatigen Bel\u00e4ge zus\u00e4tzliche Vorbereitungen treffen und die besonderen Eigenschaften des Formats bedenken.<\/p>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/urbanixx-gres-nagano-bodenfliese-betonoptik-weiss-matt-120x120-cm-rekt.-r10\/10532868\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1670 size-full\" title=\"Urbanixx Gres Nagano Bodenfliese Betonoptik Wei\u00df matt 120x120 cm rekt. R10\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/urbanixx-gres-nagano-bodenfliese-betonoptik-weiss-matt-120x120-cm-rekt.-r10.jpg\" alt=\"Urbanixx Gres Nagano Bodenfliese Betonoptik Wei\u00df matt 120x120 cm rekt. R10\" width=\"850\" height=\"567\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/urbanixx-gres-nagano-bodenfliese-betonoptik-weiss-matt-120x120-cm-rekt.-r10.jpg 850w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/urbanixx-gres-nagano-bodenfliese-betonoptik-weiss-matt-120x120-cm-rekt.-r10-300x200.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/urbanixx-gres-nagano-bodenfliese-betonoptik-weiss-matt-120x120-cm-rekt.-r10-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/a><\/p>\n<h3>Setzen Sie auf Feinsteinzeug<\/h3>\n<p style=\"text-align: justify;\">Die beste Materialwahl in diesem Gr\u00f6\u00dfenbereich ist Feinsteinzeug. Dieses Material ist besonders widerstandsf\u00e4hig und belastbar. Bei gro\u00dfen Fliesenformaten ist die Stabilit\u00e4t nat\u00fcrlich besonders wichtig, sodass die meisten XXL-Fliesen auch aus diesem besonders langlebigen Material bestehen.<\/p>\n<h3>Das ideale Werkzeug<\/h3>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.fliesen-onlineshop24.de\/bodenfliesen\/xxl-fliesen\/\">XXL-Bodenfliesen<\/a> zu verlegen, erfordert etwas mehr Geschicklichkeit als das Verlegen von gew\u00f6hnlichen Fliesenformaten. Im Grunde sind die Arbeitsschritte und Abl\u00e4ufe aber sehr \u00e4hnlich. Die besonderen Herausforderungen, die die gro\u00dfen Fliesenvarianten mit sich bringen, lassen sich aber mit dem Einsatz des optimalen Zubeh\u00f6rs und Werkzeugs deutlich einfacher meistern. Nat\u00fcrlich ben\u00f6tigt man als Werkzeug und Materialien zun\u00e4chst jenes <a href=\"https:\/\/www.fliesen-onlineshop24.de\/zubehoer\/\">Fliesenzubeh\u00f6r<\/a>, das man auch f\u00fcr Verlegearbeiten mit gew\u00f6hnlichen Fliesenformaten ben\u00f6tigt. Dies sind:<\/p>\n<ul>\n<li>Abstandskeile oder Nivellierungssystem<br \/>\n<a href=\"https:\/\/www.fliesen-onlineshop24.de\/system-leveling-nivelliersystem-zange\/21551485\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1715 size-full\" title=\"System Leveling Nivelliersystem Zange\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/system-leveling-nivelliersystem-zange.jpg\" alt=\"System Leveling Nivelliersystem Zange\" width=\"850\" height=\"567\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/system-leveling-nivelliersystem-zange.jpg 850w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/system-leveling-nivelliersystem-zange-300x200.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/system-leveling-nivelliersystem-zange-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/a><\/li>\n<li>Abziehleiste<\/li>\n<li>Fugbrett<br \/>\n<a href=\"https:\/\/www.fliesen-onlineshop24.de\/codex-fugbrett\/11524796\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1712\" title=\"Codex Fugbrett\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-Fugbrett-3.jpg\" alt=\"Codex Fugbrett\" width=\"716\" height=\"358\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-Fugbrett-3.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-Fugbrett-3-300x150.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-Fugbrett-3-768x384.jpg 768w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-Fugbrett-3-872x436.jpg 872w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><\/a><\/li>\n<li>Fugenkreuze<\/li>\n<li>Monierzange\/Kneifzange<\/li>\n<li>Schwammbrett<br \/>\n<a href=\"https:\/\/www.fliesen-onlineshop24.de\/codex-schwammbrett\/11524811\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1717 \" title=\"Codex Schwammbrett\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Codex-Schwammbrett.jpg\" alt=\"Codex Schwammbrett\" width=\"1003\" height=\"379\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Codex-Schwammbrett.jpg 958w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Codex-Schwammbrett-300x113.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Codex-Schwammbrett-768x290.jpg 768w\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" \/><\/a><\/li>\n<li>Winkelschneider<\/li>\n<li>Zahnspachtel (kleine und gro\u00dfe Zackung) oder Kleberkelle<\/li>\n<li>Eimer<\/li>\n<li>R\u00fchrwerk<\/li>\n<\/ul>\n<p>Hinzu kommen f\u00fcr die Arbeiten mit gro\u00dfformatigen Fliesenvarianten:<\/p>\n<ul>\n<li>Spezieller Fliesenschneider (dazu sp\u00e4ter mehr)<\/li>\n<li>Saugn\u00e4pfe\/Saugheber<\/li>\n<\/ul>\n<figure id=\"attachment_1662\" aria-describedby=\"caption-attachment-1662\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1662 size-full\" title=\"Spezielle Saugn\u00e4pfe helfen bei der genauen Positionierung einer gro\u00dfformatigen Fliese\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-mit-Saugnapf.jpg\" alt=\"Mann positioniert Wandfliese\" width=\"850\" height=\"567\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-mit-Saugnapf.jpg 850w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-mit-Saugnapf-300x200.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-mit-Saugnapf-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-1662\" class=\"wp-caption-text\">\u00a9 Liubomir &#8211; stock.adobe.com<\/figcaption><\/figure>\n<h3>Passendes Werkzeug zum Schneiden<\/h3>\n<p style=\"text-align: justify;\">Trotz aller Akribie bei der Planung bringt es das Gro\u00dfformat nat\u00fcrlich mit sich, dass die Bodenfliesen geschnitten werden m\u00fcssen. Je nach Gr\u00f6\u00dfe und Materialst\u00e4rke sto\u00dfen gew\u00f6hnliche Fliesenschneider an ihre Grenzen, denn die maximale Schnittl\u00e4nge ist bei den Standardschneidern oft auf nicht ausreichend. Deswegen sollte man entweder einen speziellen Schneider anschaffen oder eine Winkelschleifmaschine mit Diamantscheibe verwenden.<\/p>\n<h3>Verlegeplan sorgf\u00e4ltig planen<\/h3>\n<p style=\"text-align: justify;\">Es ist empfehlenswert, immer mindestens zu zweit zu arbeiten. Dadurch sinkt das Bruchrisiko enorm. Beim Gro\u00dfformat-Wandfliesen-Verlegen wird nicht unbedingt ein Saugnapf oder Saugheber ben\u00f6tigt, beim Verlegen auf dem Boden sollte er nicht fehlen. Beim Planen mit den gro\u00dfen Wand- oder Bodenfliesen muss man zuerst beachten, wie die Raumma\u00dfe mit der Gr\u00f6\u00dfe korrespondieren. Um gro\u00dfformatige Fliesen zu verlegen, sollte das Verlegemuster sorgsam geplant und der Materialbedarf m\u00f6glichst genau ermittelt werden. Ziel sollte es sein, den Verschnitt zu minimieren \u2013 ganz vermeiden l\u00e4sst er sich nicht. Auf jeden Fall sollte man beim Kauf der Fliesen einige Fliesen mehr kaufen als berechnet. Zum einen kann beim Schneiden immer mal eine Fliese Schaden nehmen. So hat man Ersatz, falls nach Jahren der Nutzung eine Bodenfliese kaputtgeht.<\/p>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/flaviker-nordik-stone-bodenfliese-natursteinoptik-black-anpoliert-120x120-cm-rekt.\/11462432\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1697 size-full\" title=\"Flaviker Nordik Stone Bodenfliese Natursteinoptik Black anpoliert 120x120 cm rekt.\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/flaviker-nordik-stone-bodenfliese-natursteinoptik-black-anpoliert-120x120-cm-rekt.jpg\" alt=\"Flaviker Nordik Stone Bodenfliese Natursteinoptik Black anpoliert 120x120 cm rekt.\" width=\"900\" height=\"611\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/flaviker-nordik-stone-bodenfliese-natursteinoptik-black-anpoliert-120x120-cm-rekt.jpg 900w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/flaviker-nordik-stone-bodenfliese-natursteinoptik-black-anpoliert-120x120-cm-rekt-300x204.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/flaviker-nordik-stone-bodenfliese-natursteinoptik-black-anpoliert-120x120-cm-rekt-768x521.jpg 768w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/flaviker-nordik-stone-bodenfliese-natursteinoptik-black-anpoliert-120x120-cm-rekt-110x75.jpg 110w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<div class=\"box info  \"><div class=\"box-inner-block\"><i class=\"fa tie-shortcode-boxicon\"><\/i>\n\t\t\tTipp: M\u00f6chten Sie ein besonders exaktes Fugenbild erzeugen, dann sollten Sie auf rektifizierte XXL-Boden- oder Wandfliesen setzen.\n\t\t\t<\/div><\/div>\n<h3>Boden sorgf\u00e4ltig vorbereiten<\/h3>\n<p style=\"text-align: justify;\">Bei einem gro\u00dfen, fl\u00e4chigen Fliesenformat muss auch der Boden besonders gr\u00fcndlich vorbereitet werden. Nat\u00fcrlich ist dies auch bei Verlegearbeiten mit kleineren Bodenfliesen erforderlich, doch gro\u00dfformatige Fliesenvarianten verzeihen selbst kleine Unebenheiten des Untergrunds kaum. Denn bei nicht-begradigten W\u00e4nden oder unebenen B\u00f6den entsteht bei gro\u00dfformatigen Boden- oder Wandfliesen h\u00e4ufig das Problem, dass die Fliesenkachel nicht auf der gesamten Auflagefl\u00e4che Kontakt zum Untergrund hat. Deswegen sollte der Untergrund gr\u00fcndlich begutachtet werden. Er darf keine Unebenheiten besitzen und muss gegebenenfalls gegl\u00e4ttet werden. Die H\u00f6henabweichung darf einen halben Millimeter pro laufendem Meter nicht \u00fcbersteigen. Dazu eignet sich auf dem Boden eine selbstverlaufende Zement-Bodenausgleichsmasse am besten.<\/p>\n<p><a href=\"https:\/\/www.fliesen-onlineshop24.de\/codex-fm-20-25-kg-ausgleichmasse\/11524794\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1676\" title=\"Codex FM 20 25 kg Ausgleichmasse\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-fm-20-25-kg-ausgleichmasse-146x300.png\" alt=\"Codex FM 20 25 kg Ausgleichmasse\" width=\"230\" height=\"472\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-fm-20-25-kg-ausgleichmasse-146x300.png 146w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/codex-fm-20-25-kg-ausgleichmasse.png 400w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Sollen die gro\u00dfformatigen Fliesen an der Wand angebracht werden, dann sollte diese ebenfalls begradigt werden. Auch wenn es naheliegt, f\u00fcr die Begradigung gew\u00f6hnliche Spachtelmasse zu verwenden, sollte man unbedingt speziellen Ausgleichsm\u00f6rtel verwenden, denn die meisten handels\u00fcblichen Spachtelmassen basieren auf einer Gipsmischung. Da Gips aber nach dem Austrocknen wasserempfindlich bleibt, kann dies langfristig zum Problem werden. Das gilt insbesondere in Feuchtr\u00e4umen, wo besonders h\u00e4ufig Wand- und Bodenfliesen zum Einsatz kommen. Soll die Ausgleichsmasse auf einem saugf\u00e4higen, mineralischen Untergrund aufgetragen werden, ist zus\u00e4tzlich das Aufbringen einer Grundierung empfehlenswert. Sie sollte nach den Herstellerangaben, die sich auf dem gew\u00e4hlten Fliesenkleber oder M\u00f6rtel befinden, abgestimmt werden. Eine solche Grundierung sorgt f\u00fcr eine verbesserte Haftvermittlung, Saugf\u00e4higkeitsreduzierung und tr\u00e4gt zur Staubbindung bei.<\/p>\n<figure id=\"attachment_1666\" aria-describedby=\"caption-attachment-1666\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1666 size-full\" title=\"Bei XXL-Fliesen bietet sich das Arbeiten zu zweit an\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-4.jpg\" alt=\"Gro\u00dfformatige Fliesen verlegen\" width=\"850\" height=\"568\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-4.jpg 850w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-4-300x200.jpg 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-4-768x513.jpg 768w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-4-110x75.jpg 110w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-1666\" class=\"wp-caption-text\">\u00a9 yunava1 &#8211; stock.adobe.com<\/figcaption><\/figure>\n<h3>XXL-Fliesen schneiden und einmessen<\/h3>\n<p style=\"text-align: justify;\">Nach der Vorbereitung und dem Begradigen von Boden oder Wand steht das Einmessen und Zuschneiden der Fliesen auf dem Programm. Auch ein noch so akribisch ausgearbeiteter Verlegeplan erspart diesen Arbeitsschritt leider nicht. Bei gro\u00dfformatigen Wand- oder Bodenfliesen sollte man beim Einmessen besondere Sorgfalt walten lassen, denn jede verschnittene Riesenfliese verursacht logischerweise h\u00f6here Kosten, als das bei kleinformatigen Varianten der Fall ist.<\/p>\n<figure id=\"attachment_1678\" aria-describedby=\"caption-attachment-1678\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1678 size-full\" title=\"Bei gro\u00dfformatigen Fliesen sollte man besonders vorsichtig arbeiten\" src=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grosse-Fliesen-Schneiden.png\" alt=\"Gro\u00dfformatige Fliesen verlegen\" width=\"850\" height=\"567\" srcset=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grosse-Fliesen-Schneiden.png 850w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grosse-Fliesen-Schneiden-300x200.png 300w, https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grosse-Fliesen-Schneiden-768x512.png 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-1678\" class=\"wp-caption-text\">\u00a9 New Africa &#8211; stock.adobe.com<\/figcaption><\/figure>\n<h3>Die ideale Verlegetechnik f\u00fcr XXL-Formate: das Buttering and Floating-Verfahren<\/h3>\n<p style=\"text-align: justify;\">Beim anschlie\u00dfenden Verlegen sollten Sie unbedingt auf das Buttering and Floating-Verfahren setzen. Dieses D\u00fcnnbettverfahren garantiert bei professioneller Umsetzung maximale Haft und verhindert, dass sich unter der Riesenfliese kleine Hohlr\u00e4ume bilden. Wie der Name bereits vermuten l\u00e4sst, handelt es sich bei diesem Verfahren um eine Kombination aus der Aufstrich- und der schwimmenden D\u00fcnnbettverlegetechnik. Bei dieser Technik wird auf der Unterseite der Fliesenkachel sorgf\u00e4ltig eine Schicht M\u00f6rtel aufgetragen, die glatt verstrichen wird. Anschlie\u00dfend wird die bestrichene Kachel (Buttering) auf das M\u00f6rtelbett (Floating) aufgebracht. Um gro\u00dfformatige Fliesen zu verlegen, sind Saugn\u00e4pfe beziehungsweise Saugheber zu empfehlen. Dieses Werkzeug erm\u00f6glicht das sichere Platzieren und Justieren der XXL-Fliesen. Je nach Ausma\u00df bringen die gro\u00dfformatigen Wand- oder Bodenfliesen ein Gewicht von mehr als einem Zentner auf die Waage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Tipps zum Arbeiten mit XXL-Fliesen \u00bb Scheinbar fugenlose B\u00e4der, elegante Wand- und Bodenkonzepte in Wohnr\u00e4umen \u2013 mit gro\u00dfformatigen Fliesen l\u00e4sst sich eine ruhige, klare und einzigartige Atmosph\u00e4re schaffen. Dank des geringen Fugenanteils dieser Wand- und Bodenfliesen bieten sie fantastische Gestaltungsm\u00f6glichkeiten. Ab einer Seitenl\u00e4nge von etwa 90 cm spricht man von XXL-Fliesen. Das umfasst sowohl &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[113,318,316,313,319,317,106,315,314],"class_list":["post-1652","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-inspiration-gestaltung","tag-feinsteinzeug","tag-fliesen-mit-metalloptik","tag-grosse-fliesen","tag-grossformatige-fliesen-verlegen","tag-saugnaepfe-fuer-grosse-fliesen","tag-wohnraumgestaltung","tag-xxl-fliesen","tag-xxl-format","tag-xxl-wandfliesen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gro\u00dfformatige Fliesen verlegen - Fliesen-Onlineshop24 Magazin<\/title>\n<meta name=\"description\" content=\"Worauf muss man beim Verlegen von gro\u00dfformatigen Fliesen achten? Tipps f\u00fcr \u2714Planung &amp; \u2714Verlegearbeiten in der \u00dcbersicht | Fliesen-Onlineshop24\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gro\u00dfformatige Fliesen verlegen - Fliesen-Onlineshop24 Magazin\" \/>\n<meta property=\"og:description\" content=\"Worauf muss man beim Verlegen von gro\u00dfformatigen Fliesen achten? Tipps f\u00fcr \u2714Planung &amp; \u2714Verlegearbeiten in der \u00dcbersicht | Fliesen-Onlineshop24\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/\" \/>\n<meta property=\"og:site_name\" content=\"Fliesen-Onlineshop24 Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T09:00:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-03T08:26:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wpadministrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpadministrator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/\",\"url\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/\",\"name\":\"Gro\u00dfformatige Fliesen verlegen - Fliesen-Onlineshop24 Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg\",\"datePublished\":\"2023-03-31T09:00:51+00:00\",\"dateModified\":\"2023-04-03T08:26:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7\"},\"description\":\"Worauf muss man beim Verlegen von gro\u00dfformatigen Fliesen achten? Tipps f\u00fcr \u2714Planung & \u2714Verlegearbeiten in der \u00dcbersicht | Fliesen-Onlineshop24\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#primaryimage\",\"url\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg\",\"contentUrl\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg\",\"width\":850,\"height\":507,\"caption\":\"\u00a9 Anselm - stock.adobe.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gro\u00dfformatige Fliesen verlegen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website\",\"url\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/\",\"name\":\"Fliesen-Onlineshop24 Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7\",\"name\":\"wpadministrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g\",\"caption\":\"wpadministrator\"},\"sameAs\":[\"http:\/\/magazin.fliesen-onlineshop24.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gro\u00dfformatige Fliesen verlegen - Fliesen-Onlineshop24 Magazin","description":"Worauf muss man beim Verlegen von gro\u00dfformatigen Fliesen achten? Tipps f\u00fcr \u2714Planung & \u2714Verlegearbeiten in der \u00dcbersicht | Fliesen-Onlineshop24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/","og_locale":"de_DE","og_type":"article","og_title":"Gro\u00dfformatige Fliesen verlegen - Fliesen-Onlineshop24 Magazin","og_description":"Worauf muss man beim Verlegen von gro\u00dfformatigen Fliesen achten? Tipps f\u00fcr \u2714Planung & \u2714Verlegearbeiten in der \u00dcbersicht | Fliesen-Onlineshop24","og_url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/","og_site_name":"Fliesen-Onlineshop24 Magazin","article_published_time":"2023-03-31T09:00:51+00:00","article_modified_time":"2023-04-03T08:26:15+00:00","og_image":[{"width":850,"height":507,"url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg","type":"image\/jpeg"}],"author":"wpadministrator","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"wpadministrator","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/","url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/","name":"Gro\u00dfformatige Fliesen verlegen - Fliesen-Onlineshop24 Magazin","isPartOf":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#primaryimage"},"image":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg","datePublished":"2023-03-31T09:00:51+00:00","dateModified":"2023-04-03T08:26:15+00:00","author":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7"},"description":"Worauf muss man beim Verlegen von gro\u00dfformatigen Fliesen achten? Tipps f\u00fcr \u2714Planung & \u2714Verlegearbeiten in der \u00dcbersicht | Fliesen-Onlineshop24","breadcrumb":{"@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#primaryimage","url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg","contentUrl":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-content\/uploads\/2025\/03\/Grossformatige-Fliesen-verlegen-2.jpg","width":850,"height":507,"caption":"\u00a9 Anselm - stock.adobe.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/grossformatige-fliesen-verlegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Gro\u00dfformatige Fliesen verlegen"}]},{"@type":"WebSite","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#website","url":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/","name":"Fliesen-Onlineshop24 Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/b812340af409ee29e5632c763fd3cfc7","name":"wpadministrator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/820cb88a8acec2d41bf5a2b8614b512f?s=96&d=mm&r=g","caption":"wpadministrator"},"sameAs":["http:\/\/magazin.fliesen-onlineshop24.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts\/1652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/comments?post=1652"}],"version-history":[{"count":44,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts\/1652\/revisions"}],"predecessor-version":[{"id":1773,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/posts\/1652\/revisions\/1773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/media\/1656"}],"wp:attachment":[{"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/media?parent=1652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/categories?post=1652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fliesen-onlineshop24.de\/magazin\/wp-json\/wp\/v2\/tags?post=1652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}